{"id":1392,"date":"2017-01-10T15:52:42","date_gmt":"2017-01-10T14:52:42","guid":{"rendered":"http:\/\/wassersch.eu\/corumblog\/?p=1392"},"modified":"2020-08-17T10:33:38","modified_gmt":"2020-08-17T08:33:38","slug":"yuzucello","status":"publish","type":"post","link":"https:\/\/wassersch.eu\/corumblog\/2017\/01\/yuzucello\/","title":{"rendered":"Yuzucello"},"content":{"rendered":"<p>Seit ich vor zwei Jahren in Korea war, liebe ich Yuzu-Fr\u00fcchte (<i>Citrus x junos<\/i>). Dies sind Zitronen, die haupts\u00e4chlich in China, Japan und S\u00fcdkorea wachsen, und deshalb hier eher weniger zu bekommen sind. Man kann zwar in gut sortierten Asia-L\u00e4den sowohl den koreanischen Yujacheong (\uc720\uc790\uccad &#8211; Honig mit Yuzuscheiben) als auch Yuzu-Saft bekommen, aber die frischen Fr\u00fcchte sind einfach nur genial! Dieser Geruch! <\/p>\n<p>Letztes Jahr habe ich nach langer Recherche einen Feinkostladen in der Umgebung gefunden, der bereit war, mir Yuzus zu bestellen. Zu meiner gro\u00dfen \u00dcberraschung kamen die Fr\u00fcchte dann nicht aus Asien, sondern tats\u00e4chlich aus Spanien. Nach weiterer Recherche habe ich den spanischen Produzenten auch herausgefunden und diesen Winter meine Yuzus dort direkt bestellt. Das hat soweit auch ganz prima geklappt; wenn der Paketdienst etwas zuverl\u00e4ssiger gewesen w\u00e4re, h\u00e4tte ich sie innerhalb einer Woche nach Bestellung gehabt. Die Fr\u00fcchte waren zwar immmer noch nicht billig, haben aber &#8211; auch durch eine kostenlose Dreingabe von 3 kg Mandarinen &#8211; deutlich weniger gekostet als beim H\u00e4ndler.<\/p>\n<p> <img decoding=\"async\" class=\"center\" src=\"http:\/\/www.wassersch.eu\/Blog\/Rez\/2017\/Yuzu.jpg\" alt=\"Yuzu.jpg\" title=\"Yuzus\" ><\/p>\n<p>Yuzus werden vorrangig wegen ihrer Schale verarbeitet. Die Frucht selbst hat wenig Fruchtfleisch, aber daf\u00fcr umso mehr Kerne. (Die im \u00dcbrigen extrem gut keimen!)<\/p>\n<p>Was macht man mit Schalen von Zitrusfr\u00fcchten? Richtig: man legt sie in Alkohol oder kandiert sie. Genau das habe ich getan. Genau wie man Zitronen zu Limoncello oder Orangen zu <a href=\"https:\/\/cucinaepiu.wordpress.com\/2014\/12\/31\/orancello\/\">Orancello<\/a> verarbeiten kann, habe ich eben Yuzucello produziert.<\/p>\n<p><img decoding=\"async\" class=\"center\" src=\"http:\/\/www.wassersch.eu\/Blog\/Rez\/2017\/Yuzucello1.jpg\" alt=\"Yuzucello1.jpg\" title=\"Yuzucello im Werden\" ><\/p>\n<p><img decoding=\"async\" class=\"center\" src=\"http:\/\/www.wassersch.eu\/Blog\/Rez\/2017\/Yuzucello2.jpg\" alt=\"Yuzucello2.jpg\" title=\"Fertiger Yuzucello\" ><\/p>\n<h3>Yuzucello<\/h3>\n<table border= \"0\" width= \"100%\">\n<tr>\n<td width= \"170\" align= \"left\">Quellenangabe: <\/td>\n<td>Erfasst 08.01.2017 von Sus<\/td>\n<\/tr>\n<tr>\n<td width= \"170\" align= \"left\">Kategorien: <\/td>\n<td>Yuzu, Getr\u00e4nk, Lik\u00f6r, Alkohol<\/td>\n<\/tr>\n<tr>\n<td width= \"170\" align= \"left\">Mengenangaben f&uuml;r: <\/td>\n<td>1 Rezept<\/td>\n<\/tr>\n<\/table>\n<h4>Zutaten:<\/h4>\n<table>\n<tr>\n<td width= \"50\" align= \"right\">5<\/td>\n<td width= \"120\"><\/td>\n<td>Yuzu; unbehandelt<\/td>\n<\/tr>\n<tr>\n<td width= \"50\" align= \"right\">500<\/td>\n<td width= \"120\">ml<\/td>\n<td>Alkohol (96%)<\/td>\n<\/tr>\n<tr>\n<td width= \"50\" align= \"right\">1<\/td>\n<td width= \"120\">l<\/td>\n<td>Wasser<\/td>\n<\/tr>\n<tr>\n<td width= \"50\" align= \"right\">600<\/td>\n<td width= \"120\">ml<\/td>\n<td>Zucker<\/td>\n<\/tr>\n<\/table>\n<h4>Zubereitung:<\/h4>\n<p>Yuzu sch\u00e4len und die wei\u00dfe Haut auf der Innenseite vollst\u00e4ndig entfernen. Schalen in ein gro\u00dfes Gef\u00e4\u00df geben und mit Alkohol auff\u00fcllen, dass die Schalen bedeckt sind. Gef\u00e4\u00df verschlie\u00dfen und f\u00fcr die n\u00e4chsten 8 Wochen k\u00fchl und dunkel stellen. Gelegentlich etwas sch\u00fctteln.<\/p>\n<p>Wasser mit dem Zucker aufkochen, bis der Zucker sich vollst\u00e4ndig aufgel\u00f6st hat. Abk\u00fchlen lassen.<\/p>\n<p>Den Alkohol durch ein Sieb in eine gro\u00dfe Sch\u00fcssel gie\u00dfen und mit dem Sirup vermischen. Etwas abschmecken (Zucker->s\u00fc\u00dfer, Yuzusaft->s\u00e4uerlicher) und dann in Flaschen abf\u00fcllen.<\/p>\n<h4>Anmerkung:<\/h4>\n<p> &#8211; Der Yuzucello hat einen Alkoholgehalt von ca. 30%.<\/p>\n<p> &#8211; Man kann auch 40%igen Alkohol (Wodka) verwenden, dann verwendet man weniger Sirup. Allerdings ist der Geschmack dann auch weniger intensiv.<\/p>\n<hr \/>\n<div align= \"right\"><font size= \"0.625rem\">Index: <a class= \"techtag\" href= \"http:\/\/www.wassersch.eu\/Rezepte\/Index\/Rez_XY#Yuzu\" rel= \"tag\">Yuzu<\/a>, <a class= \"techtag\" href= \"http:\/\/www.wassersch.eu\/Rezepte\/Index\/Rez_G#Getraenk\" rel= \"tag\">Getr\u00e4nk<\/a>, <a class= \"techtag\" href= \"http:\/\/www.wassersch.eu\/Rezepte\/Index\/Rez_L#Likoer\" rel= \"tag\">Lik\u00f6r<\/a>, <a class= \"techtag\" href= \"http:\/\/www.wassersch.eu\/Rezepte\/Index\/Rez_A#Alkohol\" rel= \"tag\">Alkohol<\/a><\/font> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seit ich vor zwei Jahren in Korea war, liebe ich Yuzu-Fr\u00fcchte (Citrus x junos). Dies sind Zitronen, die haupts\u00e4chlich in China, Japan und S\u00fcdkorea wachsen, und deshalb hier eher weniger zu bekommen sind. Man kann zwar in gut sortierten Asia-L\u00e4den sowohl den koreanischen Yujacheong (\uc720\uc790\uccad &#8211; Honig mit Yuzuscheiben) als auch Yuzu-Saft bekommen, aber die &hellip; <a href=\"https:\/\/wassersch.eu\/corumblog\/2017\/01\/yuzucello\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eYuzucello\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[494,2],"tags":[62,60,61,58,59],"class_list":["post-1392","post","type-post","status-publish","format-standard","hentry","category-alkohol","category-kochen-backen-und-geniessen","tag-alkohol","tag-getraenk","tag-likoer","tag-yuzu","tag-zitrus"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p923CK-ms","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/posts\/1392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/comments?post=1392"}],"version-history":[{"count":10,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/posts\/1392\/revisions"}],"predecessor-version":[{"id":2440,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/posts\/1392\/revisions\/2440"}],"wp:attachment":[{"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/media?parent=1392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/categories?post=1392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/tags?post=1392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}