{"id":112,"date":"2007-08-17T08:43:00","date_gmt":"2007-08-17T06:43:00","guid":{"rendered":"http:\/\/wassersch.eu\/corumblog\/paprika-kuerbis-gemuese-4171766\/"},"modified":"2018-10-28T13:00:39","modified_gmt":"2018-10-28T12:00:39","slug":"paprika-kuerbis-gemuese-4171766","status":"publish","type":"post","link":"https:\/\/wassersch.eu\/corumblog\/2007\/08\/paprika-kuerbis-gemuese-4171766\/","title":{"rendered":"Paprika &#8230;"},"content":{"rendered":"<p><a target= \"_blank\" ><img src= \"http:\/\/farm2.static.flickr.com\/1007\/1019199543_9168cd76c0_o.jpg\" alt= \"Garten-Koch-Event Bell Peppers - Paprika [31. August 2007]\" title= \"Garten-Koch-Event Bell Peppers - Paprika [31. August 2007]\"  class= \"left\" style=\"border-radius: 0; margin-top: 0em;\"\/><\/a>Am Wochenende wurde mal wieder der Grill f\u00fcr H&auml;hnchenfl&uuml;gel und -beine (in Zitronen-Rosmarin- Marinade) angeheizt. Eigentlich h&auml;tte &#8211; unter der Bedingung, da&szlig; <a class= \"deadlink\" title= \"http:\/\/gaertnerblog.de\/blog\/2007\/garten-koch-event-bell-peppers-paprika\/\" target= \"_blank\">Paprika<\/a> verwendet werden sollen &#8211; Ratatouille ganz gut dazu gepa&szlig;t, aber das gab&#8217;s ja <a href= \"http:\/\/corum.twoday.net\/stories\/4090324\/\">gerade erst<\/a>. Auf der Suche nach Ideen fiel mir im Gefrierschrank noch ein Paket eingefrorener K&uuml;rbisschnitze entgegen. Huch, die sollten wohl dringend verarbeitet werden, denn schlie&szlig;lich sind ja bald die neuen K&uuml;rbisse reif. Angeregt durch ein Rezept aus der <strike>aktuellen<\/strike> letzten Ausgabe der Zeitschrift <a href= \"http:\/\/www.krautundrueben.de\" target= \"_blank\">Kraut &#038; R&uuml;ben<\/a> (&#8222;Paprika-Wirsing-Gem&uuml;se&#8220;) gab es bei uns &#8222;Paprika-K&uuml;rbis-Gem&uuml;se&#8220;.<\/p>\n<p>(Leider waren von den sechs gekauften, wundersch&ouml;n aussehenden roten Paprikas drei innen total schimmelig. Deshalb ist der Rot-Anteil auf dem Bild nicht so hoch wie er sein sollte.)<\/p>\n<p><img src= \"http:\/\/www.wassersch.eu\/Blog\/Rez\/Paprika-Kuerbis-Gemuese.jpg\" alt= \"Paprika-Kuerbis-Gemuese.jpg\" title= \"Paprika-K&uuml;rbis-Gem&uuml;se\" class=\"center\"\/><\/p>\n<p><a name= \"Paprika-K&uuml;rbis-Gem&uuml;se\"><\/a><\/p>\n<h3>Paprika-K&uuml;rbis-Gem&uuml;se<\/h3>\n<table border= \"0\" width= \"100%\">\n<tr>\n<td width= \"200\" align= \"left\">Quellenangabe: <\/td>\n<td>Angelehnt an ein Rezept aus Kraut&amp;R&uuml;ben 08\/2007<\/td>\n<\/tr>\n<tr>\n<td width= \"150\" align= \"left\"><\/td>\n<td>12.08.2007 von Sus<\/td>\n<\/tr>\n<tr>\n<td width=\"150\" align=\"left\">Kategorien: <\/td>\n<td>Beilage, Gem&uuml;se, Paprika, K&uuml;rbis<\/td>\n<\/tr>\n<tr>\n<td width=\"150\" align=\"left\"><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td width=\"150\" align=\"left\">Mengenangaben f&uuml;r: <\/td>\n<td>4 Portionen<\/td>\n<\/tr>\n<\/table>\n<h4>Zutaten:<\/h4>\n<table>\n<tr>\n<td width=\"70\" align=\"right\">600<\/td>\n<td width=\"130\">Gramm<\/td>\n<td>K&uuml;rbis<\/td>\n<\/tr>\n<tr>\n<td width=\"50\" align=\"right\">5<\/td>\n<td width=\"100\"><\/td>\n<td>Rote Paprika<\/td>\n<\/tr>\n<tr>\n<td width=\"50\" align=\"right\">1-2<\/td>\n<td width=\"100\"><\/td>\n<td>Rote Chilischoten, frisch (je nach Sch&auml;rfe mehr oder weniger)<\/td>\n<\/tr>\n<tr>\n<td width=\"50\" align=\"right\">2<\/td>\n<td width=\"100\"><\/td>\n<td>Zwiebeln<\/td>\n<\/tr>\n<tr>\n<td width=\"50\" align=\"right\">3<\/td>\n<td width=\"100\"><\/td>\n<td>Knoblauchzehen<\/td>\n<\/tr>\n<tr>\n<td width=\"50\" align=\"right\">100<\/td>\n<td width=\"100\">Gramm<\/td>\n<td>Cashewkerne<\/td>\n<\/tr>\n<tr>\n<td width=\"50\" align=\"right\">1<\/td>\n<td width=\"100\"><\/td>\n<td>Zitrone, Saft davon<\/td>\n<\/tr>\n<tr>\n<td width=\"50\" align=\"right\">1<\/td>\n<td width=\"100\">Teel&ouml;ffel<\/td>\n<td>Koriandersamen; zersto&szlig;en<\/td>\n<\/tr>\n<tr>\n<td width=\"50\" align=\"right\">1<\/td>\n<td width=\"100\">Essl&ouml;ffel<\/td>\n<td>Instant-Br&uuml;hen-Pulver<\/td>\n<\/tr>\n<tr>\n<td width=\"50\" align=\"right\"><\/td>\n<td width=\"100\"><\/td>\n<td>Salz, Pfeffer<\/td>\n<\/tr>\n<tr>\n<td width=\"50\" align=\"right\">1<\/td>\n<td width=\"100\">Handvoll<\/td>\n<td>Zitronenmelisse; gehackt<\/td>\n<\/tr>\n<\/tr>\n<\/table>\n<h4>Zubereitung:<\/h4>\n<p>Die Cashewkerne in einer trockenen Pfanne r&ouml;sten und kleinhacken. Beiseite legen.<\/p>\n<p>Das K&uuml;rbisfleisch in ca. 1 cm gro\u00dfe W&uuml;rfel schneiden. Die Paprika putzen und in ebenso gro&szlig;e St&uuml;cke schneiden. Die gesch&auml;lten und kleingeschnittenen Zwiebeln und Knoblauch in einem Topf mit etwas &Ouml;l glasig d&uuml;nsten. Paprika dazugeben, ein paar Minuten sp&auml;ter die K&uuml;rbisst&uuml;cke. Sobald diese Wasser gezogen haben, die Instant-Br&uuml;he einr&uuml;hren. Die anderen Gew&uuml;rze und die Cashewkerne hinzugeben. Solange k&ouml;cheln lassen, bis der K&uuml;rbis leicht zerf&auml;llt; die Paprikast&uuml;cke sollten noch fester sein. <\/p>\n<p>Kurz vor dem Servieren die gehackte Zitronenmelisse unterheben.<\/p>\n<h4>Anmerkung:<\/h4>\n<p>&#8211; Bei den Chilischoten lieber nicht ganz so scharfe, aber daf&uuml;r mehr verwenden.<\/p>\n<hr \/>\n<div class= \"snap_nopreview\" align= \"right\"><font size= \"1\">Index:<a class= \"techtag\" href= \"http:\/\/www.wassersch.eu\/Rezepte\/Index\/Rez_P#Paprika\" rel= \"tag\">Paprika<\/a>, <a class= \"techtag\" href= \"http:\/\/www.wassersch.eu\/Rezepte\/Index\/Rez_K#Kuerbis\" rel= \"tag\">K&uuml;rbis<\/a>, <a class= \"techtag\" href=\"http:\/\/www.wassersch.eu\/Rezepte\/Index\/Rez_B#Beilage\" rel= \"tag\">Beilage<\/a>, <a class= \"techtag\" href= \"http:\/\/www.wassersch.eu\/Rezepte\/Index\/Rez_B#Blog-Event\" rel= \"tag\">Blog-Event<\/a> <\/font> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Am Wochenende wurde mal wieder der Grill f\u00fcr H&auml;hnchenfl&uuml;gel und -beine (in Zitronen-Rosmarin- Marinade) angeheizt. Eigentlich h&auml;tte &#8211; unter der Bedingung, da&szlig; Paprika verwendet werden sollen &#8211; Ratatouille ganz gut dazu gepa&szlig;t, aber das gab&#8217;s ja gerade erst. Auf der Suche nach Ideen fiel mir im Gefrierschrank noch ein Paket eingefrorener K&uuml;rbisschnitze entgegen. Huch, die &hellip; <a href=\"https:\/\/wassersch.eu\/corumblog\/2007\/08\/paprika-kuerbis-gemuese-4171766\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201ePaprika &#8230;\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[124,44,433,31,81],"class_list":["post-112","post","type-post","status-publish","format-standard","hentry","category-kochen-backen-und-geniessen","tag-beilage","tag-blog-event","tag-cashew","tag-kuerbis","tag-paprika"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p923CK-1O","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/posts\/112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/comments?post=112"}],"version-history":[{"count":2,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/posts\/112\/revisions"}],"predecessor-version":[{"id":3607,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/posts\/112\/revisions\/3607"}],"wp:attachment":[{"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/media?parent=112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/categories?post=112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wassersch.eu\/corumblog\/wp-json\/wp\/v2\/tags?post=112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}